{"id":234,"date":"2017-11-08T21:11:37","date_gmt":"2017-11-08T20:11:37","guid":{"rendered":"http:\/\/spv-meissen.de\/?p=234"},"modified":"2022-01-23T20:15:47","modified_gmt":"2022-01-23T19:15:47","slug":"kochspass-vitry-in-meissen-2017","status":"publish","type":"post","link":"https:\/\/spv-meissen.de\/cs\/2017\/11\/08\/kochspass-vitry-in-meissen-2017\/","title":{"rendered":"Kochspa\u00df Vitry in Mei\u00dfen 2017"},"content":{"rendered":"<p>Es gibt ihn wieder, den vom St\u00e4dtepartnerschaftsverein Mei\u00dfen e. V. organisierten Kochspa\u00df. In den Winterferien wurde in R\u00e4umlichkeiten der Stiftung Soziale Projekte franz\u00f6sisch gekocht.<\/p>\n<p>Unter der Anleitung von Mitgliedern des SPV kreierten die Feriensch\u00fcler ein Drei-G\u00e4nge-Men\u00fc. Jeder dieser drei G\u00e4nge wurde von jeweils einer Gruppe vorbereitet. Nach flei\u00dfigem Schneiden, Hacken, R\u00fchren, Braten oder Kochen lie\u00dfen sich alle den mit Baguette gereichten Salat schmecken, w\u00e4hrend der Hauptgang, das H\u00e2chis parmentier, noch im Ofen fertig buk. Nach den beiden herzhaften G\u00e4ngen warteten s\u00fc\u00dfe Cr\u00eapes auf die Liebhaber der franz\u00f6sischen K\u00fcche.<\/p>\n<p>W\u00e4hrend des Kochens und des Essens gab es interessante Gespr\u00e4che \u00fcber die franz\u00f6sische Kultur und Landeskunde. Franz\u00f6sische Musik rundete die gem\u00fctliche Atmosph\u00e4re ab.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es gibt ihn wieder, den vom St\u00e4dtepartnerschaftsverein Mei\u00dfen e. V. organisierten Kochspa\u00df. In den Winterferien wurde in R\u00e4umlichkeiten der Stiftung Soziale Projekte franz\u00f6sisch gekocht. Unter der Anleitung von Mitgliedern des SPV kreierten die Feriensch\u00fcler ein Drei-G\u00e4nge-Men\u00fc. Jeder dieser drei G\u00e4nge wurde von jeweils einer Gruppe vorbereitet. Nach flei\u00dfigem Schneiden, Hacken, R\u00fchren, Braten oder Kochen lie\u00dfen sich alle den mit Baguette gereichten Salat schmecken, w\u00e4hrend der Hauptgang, das H\u00e2chis parmentier, noch im Ofen fertig buk. Nach den beiden herzhaften G\u00e4ngen warteten s\u00fc\u00dfe Cr\u00eapes auf die Liebhaber der franz\u00f6sischen K\u00fcche. W\u00e4hrend des Kochens und des Essens gab es interessante Gespr\u00e4che \u00fcber die franz\u00f6sische Kultur und Landeskunde. Franz\u00f6sische Musik rundete die gem\u00fctliche Atmosph\u00e4re ab.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[31],"tags":[],"class_list":["post-234","post","type-post","status-publish","format-standard","hentry","category-kochspass"],"translation":{"provider":"WPGlobus","version":"3.0.5","language":"cs","enabled_languages":["de","fr","ja","el","cs","en","pl"],"languages":{"de":{"title":true,"content":true,"excerpt":false},"fr":{"title":false,"content":false,"excerpt":false},"ja":{"title":false,"content":false,"excerpt":false},"el":{"title":false,"content":false,"excerpt":false},"cs":{"title":false,"content":false,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false},"pl":{"title":false,"content":false,"excerpt":false}}},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/spv-meissen.de\/cs\/wp-json\/wp\/v2\/posts\/234","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spv-meissen.de\/cs\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/spv-meissen.de\/cs\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/spv-meissen.de\/cs\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/spv-meissen.de\/cs\/wp-json\/wp\/v2\/comments?post=234"}],"version-history":[{"count":4,"href":"https:\/\/spv-meissen.de\/cs\/wp-json\/wp\/v2\/posts\/234\/revisions"}],"predecessor-version":[{"id":1316,"href":"https:\/\/spv-meissen.de\/cs\/wp-json\/wp\/v2\/posts\/234\/revisions\/1316"}],"wp:attachment":[{"href":"https:\/\/spv-meissen.de\/cs\/wp-json\/wp\/v2\/media?parent=234"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/spv-meissen.de\/cs\/wp-json\/wp\/v2\/categories?post=234"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/spv-meissen.de\/cs\/wp-json\/wp\/v2\/tags?post=234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}