{"id":2511,"date":"2025-09-05T20:00:00","date_gmt":"2025-09-05T18:00:00","guid":{"rendered":"https:\/\/spv-meissen.de\/?p=2511"},"modified":"2026-01-05T16:37:16","modified_gmt":"2026-01-05T15:37:16","slug":"sommerfest-2025","status":"publish","type":"post","link":"https:\/\/spv-meissen.de\/ja\/2025\/09\/05\/sommerfest-2025\/","title":{"rendered":"Erstes Baumpatenschaftsfest &#8211; 2025"},"content":{"rendered":"<p>Als Verein mit inzwischen zwei Baumpatenschaften haben wir uns \u00fcber die Einladung des Amtes f\u00fcr Stadtplanung und -entwicklung zum ersten Baumpatenschaftsfest im Nikolaipark sehr gefreut. <br \/>In einer sehr angenehmen Atmosph\u00e4re wurden die vielf\u00e4ltigen Geschichten und Beweggr\u00fcnde hinter den einzelnen Baumpatenschaften kommuniziert. Unsere beiden B\u00e4ume sind die Japanische Nelkenkirsche am Altstadteingang und der Baumflieder im kleinen Park am K\u00e4ndlerbrunnen. Sie symbolisieren 25 Jahre St\u00e4dtepartnerschaftsverein Mei\u00dfen e.V. und 60 Jahre St\u00e4dtepartnerschaft Vitry-sur-Seine und Mei\u00dfen.<br \/>Das Fest war ein sehr sch\u00f6nes Treffen von Menschen, die sich f\u00fcr eine gr\u00fcne und lebenswerte Stadt engagieren.<\/p>\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"771\" height=\"1024\" data-id=\"2555\" src=\"https:\/\/spv-meissen.de\/wp-content\/uploads\/2025\/06\/PXL_20250905_131859239-771x1024.jpg\" alt=\"\" class=\"wp-image-2555\" srcset=\"https:\/\/spv-meissen.de\/wp-content\/uploads\/2025\/06\/PXL_20250905_131859239-771x1024.jpg 771w, https:\/\/spv-meissen.de\/wp-content\/uploads\/2025\/06\/PXL_20250905_131859239-226x300.jpg 226w, https:\/\/spv-meissen.de\/wp-content\/uploads\/2025\/06\/PXL_20250905_131859239-768x1020.jpg 768w, https:\/\/spv-meissen.de\/wp-content\/uploads\/2025\/06\/PXL_20250905_131859239-75x100.jpg 75w\" sizes=\"(max-width: 771px) 100vw, 771px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"609\" height=\"1024\" data-id=\"2557\" src=\"https:\/\/spv-meissen.de\/wp-content\/uploads\/2025\/06\/Screenshot_20250906-104325-609x1024.png\" alt=\"\" class=\"wp-image-2557\" srcset=\"https:\/\/spv-meissen.de\/wp-content\/uploads\/2025\/06\/Screenshot_20250906-104325-609x1024.png 609w, https:\/\/spv-meissen.de\/wp-content\/uploads\/2025\/06\/Screenshot_20250906-104325-178x300.png 178w, https:\/\/spv-meissen.de\/wp-content\/uploads\/2025\/06\/Screenshot_20250906-104325-768x1292.png 768w, https:\/\/spv-meissen.de\/wp-content\/uploads\/2025\/06\/Screenshot_20250906-104325-913x1536.png 913w, https:\/\/spv-meissen.de\/wp-content\/uploads\/2025\/06\/Screenshot_20250906-104325-59x100.png 59w, https:\/\/spv-meissen.de\/wp-content\/uploads\/2025\/06\/Screenshot_20250906-104325.png 1059w\" sizes=\"(max-width: 609px) 100vw, 609px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"630\" height=\"1024\" data-id=\"2556\" src=\"https:\/\/spv-meissen.de\/wp-content\/uploads\/2025\/06\/Screenshot_20250906-104335-630x1024.png\" alt=\"\" class=\"wp-image-2556\" srcset=\"https:\/\/spv-meissen.de\/wp-content\/uploads\/2025\/06\/Screenshot_20250906-104335-630x1024.png 630w, https:\/\/spv-meissen.de\/wp-content\/uploads\/2025\/06\/Screenshot_20250906-104335-185x300.png 185w, https:\/\/spv-meissen.de\/wp-content\/uploads\/2025\/06\/Screenshot_20250906-104335-768x1248.png 768w, https:\/\/spv-meissen.de\/wp-content\/uploads\/2025\/06\/Screenshot_20250906-104335-945x1536.png 945w, https:\/\/spv-meissen.de\/wp-content\/uploads\/2025\/06\/Screenshot_20250906-104335-62x100.png 62w, https:\/\/spv-meissen.de\/wp-content\/uploads\/2025\/06\/Screenshot_20250906-104335.png 1174w\" sizes=\"(max-width: 630px) 100vw, 630px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Als Verein mit inzwischen zwei Baumpatenschaften haben wir uns \u00fcber die Einladung des Amtes f\u00fcr Stadtplanung und -entwicklung zum ersten Baumpatenschaftsfest im Nikolaipark sehr gefreut. In einer sehr angenehmen Atmosph\u00e4re wurden die vielf\u00e4ltigen Geschichten und Beweggr\u00fcnde hinter den einzelnen Baumpatenschaften kommuniziert. Unsere beiden B\u00e4ume sind die Japanische Nelkenkirsche am Altstadteingang und der Baumflieder im kleinen Park am K\u00e4ndlerbrunnen. Sie symbolisieren 25 Jahre St\u00e4dtepartnerschaftsverein Mei\u00dfen e.V. und 60 Jahre St\u00e4dtepartnerschaft Vitry-sur-Seine und Mei\u00dfen.Das Fest war ein sehr sch\u00f6nes Treffen von Menschen, die sich f\u00fcr eine gr\u00fcne und lebenswerte Stadt engagieren.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[29],"tags":[],"class_list":["post-2511","post","type-post","status-publish","format-standard","hentry","category-veranstaltungen"],"translation":{"provider":"WPGlobus","version":"3.0.5","language":"ja","enabled_languages":["de","fr","ja","el","cs","en","pl"],"languages":{"de":{"title":true,"content":true,"excerpt":false},"fr":{"title":false,"content":false,"excerpt":false},"ja":{"title":false,"content":false,"excerpt":false},"el":{"title":false,"content":false,"excerpt":false},"cs":{"title":false,"content":false,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false},"pl":{"title":false,"content":false,"excerpt":false}}},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/spv-meissen.de\/ja\/wp-json\/wp\/v2\/posts\/2511","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spv-meissen.de\/ja\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/spv-meissen.de\/ja\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/spv-meissen.de\/ja\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/spv-meissen.de\/ja\/wp-json\/wp\/v2\/comments?post=2511"}],"version-history":[{"count":2,"href":"https:\/\/spv-meissen.de\/ja\/wp-json\/wp\/v2\/posts\/2511\/revisions"}],"predecessor-version":[{"id":2558,"href":"https:\/\/spv-meissen.de\/ja\/wp-json\/wp\/v2\/posts\/2511\/revisions\/2558"}],"wp:attachment":[{"href":"https:\/\/spv-meissen.de\/ja\/wp-json\/wp\/v2\/media?parent=2511"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/spv-meissen.de\/ja\/wp-json\/wp\/v2\/categories?post=2511"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/spv-meissen.de\/ja\/wp-json\/wp\/v2\/tags?post=2511"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}