{"id":1677,"date":"2022-05-08T23:00:00","date_gmt":"2022-05-08T21:00:00","guid":{"rendered":"https:\/\/spv-meissen.de\/?p=1677"},"modified":"2022-05-15T15:53:49","modified_gmt":"2022-05-15T13:53:49","slug":"35jaehriges-jubilaeum-staedtepartnerschaft-fellbach-meissen","status":"publish","type":"post","link":"https:\/\/spv-meissen.de\/pl\/2022\/05\/08\/35jaehriges-jubilaeum-staedtepartnerschaft-fellbach-meissen\/","title":{"rendered":"35j\u00e4hriges Jubil\u00e4um St\u00e4dtepartnerschaft Fellbach &#8211; Mei\u00dfen"},"content":{"rendered":"<p>Die Stadt Fellbach lud am 8. Mai 2022 zur Matin\u00e9e des St\u00e4dtepartnerschaftsvereins Fellbach und der Stadt Fellbach im Gro\u00dfen Saal des Rathauses Fellbach ein. Der Oberb\u00fcrgermeister der Stadt Mei\u00dfen Herr Raschke und B\u00e4rbel Ramminger und Beatrice Saske als Vertreterinnen unseres SPV Mei\u00dfen e.V. sind der Einladung gern gefolgt. <br \/>Nach dem musikalischen Auftakt mit Benjakob, der das Programm auch weiter musikalisch begleitete, begr\u00fc\u00dfte die 1. Vorsitzende des SPV Fellbach e.V., Beatrix Kant die G\u00e4ste. Gerlinde K\u00e4mmerer aus Leipzig hielt einen kurzweiligen Gastvortrag zu Louise Otto-Peters, Mei\u00dfens ber\u00fchmtester Tochter. Anschlie\u00dfend lud der B\u00fcrgermeister Herr Berner nach seinem Schlusswort zum St\u00e4nderling ein.<br \/>Die G\u00e4ste der St\u00e4dtepartnerschaftsvereine und die am Programm Mitwirkenden sa\u00dfen bei guten Gespr\u00e4chen und gutem Essen noch bis in den Nachmittag beim &#8222;Zum Hirschen&#8221; und lie\u00dfen den festlichen Sonntag ausklingen.<\/p>\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"505\" data-id=\"1678\" src=\"https:\/\/spv-meissen.de\/wp-content\/uploads\/2022\/05\/08.05.2022-1024x505.jpg\" alt=\"\" class=\"wp-image-1678\" srcset=\"https:\/\/spv-meissen.de\/wp-content\/uploads\/2022\/05\/08.05.2022-1024x505.jpg 1024w, https:\/\/spv-meissen.de\/wp-content\/uploads\/2022\/05\/08.05.2022-300x148.jpg 300w, https:\/\/spv-meissen.de\/wp-content\/uploads\/2022\/05\/08.05.2022-768x379.jpg 768w, https:\/\/spv-meissen.de\/wp-content\/uploads\/2022\/05\/08.05.2022-203x100.jpg 203w, https:\/\/spv-meissen.de\/wp-content\/uploads\/2022\/05\/08.05.2022.jpg 1333w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Stadt Fellbach lud am 8. Mai 2022 zur Matin\u00e9e des St\u00e4dtepartnerschaftsvereins Fellbach und der Stadt Fellbach im Gro\u00dfen Saal des Rathauses Fellbach ein. Der Oberb\u00fcrgermeister der Stadt Mei\u00dfen Herr Raschke und B\u00e4rbel Ramminger und Beatrice Saske als Vertreterinnen unseres SPV Mei\u00dfen e.V. sind der Einladung gern gefolgt. Nach dem musikalischen Auftakt mit Benjakob, der das Programm auch weiter musikalisch begleitete, begr\u00fc\u00dfte die 1. Vorsitzende des SPV Fellbach e.V., Beatrix Kant die G\u00e4ste. Gerlinde K\u00e4mmerer aus Leipzig hielt einen kurzweiligen Gastvortrag zu Louise Otto-Peters, Mei\u00dfens ber\u00fchmtester Tochter. Anschlie\u00dfend lud der B\u00fcrgermeister Herr Berner nach seinem Schlusswort zum St\u00e4nderling ein.Die G\u00e4ste der St\u00e4dtepartnerschaftsvereine und die am Programm Mitwirkenden sa\u00dfen bei guten Gespr\u00e4chen und gutem Essen noch bis in den Nachmittag beim &#8222;Zum Hirschen&#8221; und lie\u00dfen den festlichen Sonntag ausklingen.<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1677","post","type-post","status-publish","format-standard","hentry","category-sonstiges"],"translation":{"provider":"WPGlobus","version":"3.0.5","language":"pl","enabled_languages":["de","fr","ja","el","cs","en","pl"],"languages":{"de":{"title":true,"content":true,"excerpt":false},"fr":{"title":false,"content":false,"excerpt":false},"ja":{"title":false,"content":false,"excerpt":false},"el":{"title":false,"content":false,"excerpt":false},"cs":{"title":false,"content":false,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false},"pl":{"title":false,"content":false,"excerpt":false}}},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/spv-meissen.de\/pl\/wp-json\/wp\/v2\/posts\/1677","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spv-meissen.de\/pl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/spv-meissen.de\/pl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/spv-meissen.de\/pl\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/spv-meissen.de\/pl\/wp-json\/wp\/v2\/comments?post=1677"}],"version-history":[{"count":2,"href":"https:\/\/spv-meissen.de\/pl\/wp-json\/wp\/v2\/posts\/1677\/revisions"}],"predecessor-version":[{"id":1681,"href":"https:\/\/spv-meissen.de\/pl\/wp-json\/wp\/v2\/posts\/1677\/revisions\/1681"}],"wp:attachment":[{"href":"https:\/\/spv-meissen.de\/pl\/wp-json\/wp\/v2\/media?parent=1677"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/spv-meissen.de\/pl\/wp-json\/wp\/v2\/categories?post=1677"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/spv-meissen.de\/pl\/wp-json\/wp\/v2\/tags?post=1677"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}