{"id":229,"date":"2017-04-01T20:50:35","date_gmt":"2017-04-01T18:50:35","guid":{"rendered":"http:\/\/spv-meissen.de\/?p=229"},"modified":"2022-01-23T20:17:44","modified_gmt":"2022-01-23T19:17:44","slug":"jugendsymposium-in-erba-2017","status":"publish","type":"post","link":"https:\/\/spv-meissen.de\/pl\/2017\/04\/01\/jugendsymposium-in-erba-2017\/","title":{"rendered":"Jugendsymposium in Erba 2017"},"content":{"rendered":"<p>Drau\u00dfen ist es noch sehr dunkel, als sich die kleine Reisegruppe mit achtzehn Jugendlichen aus Mei\u00dfen und drei Begleiterinnen am 22. Februar 2017 am Busbahnhof trifft. P\u00fcnktlich um sechs startet f\u00fcr diese aufgeregten Austauschsch\u00fcler der Bus. Er f\u00e4hrt sie nach Erba zum Jugendsymposium, zu welchem die Partnerstadt von Fellbach zwanzig junge Mei\u00dfner eingeladen hat. Die Sch\u00fcler des Franziskaneums, des Beruflichen Gymnasiums des BSZ Mei\u00dfen \u2013 Radebeul, des Beruflichen Gymnasiums der Freien Werkschule und des Jugendstadtrates werden gemeinsam mit Jugendlichen aus den anderen Partnerst\u00e4dten Fellbachs, Tournon, Tain l\u2019Hermitage und Pesz f\u00fcnf Tage verbringen.<\/p>\n<p>Hinter den gewaltigen Alpen mit ihren letzten sch\u00f6nen Schneem\u00fctzen, abenteuerlustigen Skifahren und kleinen Bergh\u00fctten wartet eine mediterrane und warme Lombardei. Wir bemerken sofort die sonnige Atmosph\u00e4re, die gelben und roten H\u00e4user und hier und da auch kleine Palmen. Endlich nach dreizehn Stunden Fahrt werden wir Mei\u00dfner in der Herberge \u201ePadri Barnabiti\u201c herzlich empfangen. Die Vertreter der Stadt und des St\u00e4dtepartnerschaftsvereines halten kurze Reden und begr\u00fc\u00dfen die vielen jungen G\u00e4ste.<\/p>\n<p>Nach der ersten Nacht sind alle ausgeruht bereit f\u00fcr den Arbeitstag. Der Psychologe, Herr Dr. Andrea Carta, h\u00e4lt einen Vortrag \u00fcber die Jugendsozialisation und deren Probleme. Eine Dolmetscherin \u00fcbertr\u00e4gt die Information in die englische Sprache, welche als Bedingung von allen Jugendlichen beherrscht werden soll. In kleinen internationalen Gruppen erarbeiten wir gemeinsam Vorschl\u00e4ge, wie sich junge Menschen aus aller Welt besser miteinander vernetzen k\u00f6nnen. Nach der Pr\u00e4sentation der Ergebnisse fahren alle in die Pizzeria \u201eTourl\u00e9\u201c und st\u00e4rken sich bei so viel Pizza wie sie m\u00f6gen.<\/p>\n<p>Der Freitag ist ganz und gar der Erkundung der Region gewidmet. Am Morgen wandern alle am Segrinosee entlang zur bekannten Konditorei \u201eNocciolini di Canzo\u201c, um deren K\u00f6stlichkeiten an einem extra f\u00fcr uns gedecktem B\u00fcffet zu verkosten. Am Nachmittag steht eine Bootsfahrt auf dem Comosee im Programm. Wir k\u00f6nnen viele kleine St\u00e4dtchen sehen und legen eine Zwischenstation in Torno und Cernobbio ein um das Flair zu genie\u00dfen. Auch in Como haben wir noch etwas Zeit und schauen uns das historische Stadtzentrum an, bevor wir am Abend im Castello di Pomerio von der B\u00fcrgermeisterin von Erba, Signora Tili, begr\u00fc\u00dft und zum Abendessen eingeladen werden.<\/p>\n<p>Der interessanteste Tag ist der Samstag. Mit einem \u201eSport frei\u201c und Zumba beginnt der Tag im Sportzentrum \u201ePalaerba\u201c. Die rhythmischen Bewegungen beim Zumba bereiten allen viel Spa\u00df und auch die Herren geben sich viel M\u00fche. Im Anschluss ringen die internationalen Teams bei Volleyball, Basketball und Tischtennis um die Pl\u00e4tze. Nach dem Mittag gibt es eine Unterweisung im Kampfsport und einen Athletikwettkampf.<\/p>\n<p>Der Abend dieses das Gemeinschaftsgef\u00fchl st\u00e4rkenden Samstags findet im Castello di Monguzzo bei einem k\u00f6stlichen Abschiedsdinner statt. Im Anschluss legt ein DJ f\u00fcr uns feierw\u00fctigen Jugendlichen auf. Es werden viele Abschiedsworte gesprochen und so manche Tr\u00e4ne verdr\u00fcckt. Bis Mitternacht wird gefeiert. Die letzte Nacht in der Herberge f\u00e4llt sehr kurz aus, denn am Morgen geht es nach einem ausgelassenen Fr\u00fchst\u00fcck und einem letzten Gruppenfoto p\u00fcnktlich zur\u00fcck in die Heimat.<\/p>\n<p>Die f\u00fcnf Tage waren unheimlich interessant und wir konnten verschiedene andere Kulturen kennenlernen. Projekte wie dieses lassen uns Jugendliche aktiv an der Sozialisation teilhaben und f\u00f6rdern das Gemeinschaftsgef\u00fchl.<\/p>\n<p>Herzlichen Dank an die St\u00e4dte Erba, Fellbach und Mei\u00dfen f\u00fcr diese gro\u00dfartige Chance.<\/p>\n<p><em>Vivien Frenzel, Berufliches Gymnasium BSZ Mei\u00dfen &#8211; Radebeul<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Drau\u00dfen ist es noch sehr dunkel, als sich die kleine Reisegruppe mit achtzehn Jugendlichen aus Mei\u00dfen und drei Begleiterinnen am 22. Februar 2017 am Busbahnhof trifft. P\u00fcnktlich um sechs startet f\u00fcr diese aufgeregten Austauschsch\u00fcler der Bus. Er f\u00e4hrt sie nach Erba zum Jugendsymposium, zu welchem die Partnerstadt von Fellbach zwanzig junge Mei\u00dfner eingeladen hat. Die Sch\u00fcler des Franziskaneums, des Beruflichen Gymnasiums des BSZ Mei\u00dfen \u2013 Radebeul, des Beruflichen Gymnasiums der Freien Werkschule und des Jugendstadtrates werden gemeinsam mit Jugendlichen aus den anderen Partnerst\u00e4dten Fellbachs, Tournon, Tain l\u2019Hermitage und Pesz f\u00fcnf Tage verbringen. Hinter den gewaltigen Alpen mit ihren letzten sch\u00f6nen Schneem\u00fctzen, abenteuerlustigen Skifahren und kleinen Bergh\u00fctten wartet eine mediterrane und warme Lombardei. Wir bemerken sofort die sonnige Atmosph\u00e4re, die gelben und roten H\u00e4user und hier und da auch kleine Palmen. Endlich nach dreizehn Stunden Fahrt werden wir Mei\u00dfner in der Herberge \u201ePadri Barnabiti\u201c herzlich empfangen. Die Vertreter der Stadt und des St\u00e4dtepartnerschaftsvereines halten kurze Reden und begr\u00fc\u00dfen die vielen jungen G\u00e4ste. Nach der ersten Nacht sind alle ausgeruht bereit f\u00fcr den Arbeitstag. Der Psychologe, Herr Dr. Andrea Carta, h\u00e4lt einen Vortrag \u00fcber die Jugendsozialisation und deren Probleme. Eine Dolmetscherin \u00fcbertr\u00e4gt die Information in die englische Sprache, welche als Bedingung von allen Jugendlichen beherrscht werden soll. In kleinen internationalen Gruppen erarbeiten wir gemeinsam Vorschl\u00e4ge, wie sich junge Menschen aus aller Welt besser miteinander vernetzen k\u00f6nnen. Nach der Pr\u00e4sentation der Ergebnisse fahren alle in die Pizzeria \u201eTourl\u00e9\u201c und st\u00e4rken sich bei so viel Pizza wie sie m\u00f6gen. Der Freitag ist ganz und gar der Erkundung der Region gewidmet. Am Morgen wandern alle am Segrinosee entlang zur bekannten Konditorei \u201eNocciolini di Canzo\u201c, um deren K\u00f6stlichkeiten an einem extra f\u00fcr uns gedecktem B\u00fcffet zu verkosten. Am Nachmittag steht eine Bootsfahrt auf dem Comosee im Programm. Wir k\u00f6nnen viele kleine St\u00e4dtchen sehen und legen eine Zwischenstation in Torno und Cernobbio ein um das Flair zu genie\u00dfen. Auch in Como haben wir noch etwas Zeit und schauen uns das historische Stadtzentrum an, bevor wir am Abend im Castello di Pomerio von der B\u00fcrgermeisterin von Erba, Signora Tili, begr\u00fc\u00dft und zum Abendessen eingeladen werden. Der interessanteste Tag ist der Samstag. Mit einem \u201eSport frei\u201c und Zumba beginnt der Tag im Sportzentrum \u201ePalaerba\u201c. Die rhythmischen Bewegungen beim Zumba bereiten allen viel Spa\u00df und auch die Herren geben sich viel M\u00fche. Im Anschluss ringen die internationalen Teams bei Volleyball, Basketball und Tischtennis um die Pl\u00e4tze. Nach dem Mittag gibt es eine Unterweisung im Kampfsport und einen Athletikwettkampf. Der Abend dieses das Gemeinschaftsgef\u00fchl st\u00e4rkenden Samstags findet im Castello di Monguzzo bei einem k\u00f6stlichen Abschiedsdinner statt. Im Anschluss legt ein DJ f\u00fcr uns feierw\u00fctigen Jugendlichen auf. Es werden viele Abschiedsworte gesprochen und so manche Tr\u00e4ne verdr\u00fcckt. Bis Mitternacht wird gefeiert. Die letzte Nacht in der Herberge f\u00e4llt sehr kurz aus, denn am Morgen geht es nach einem ausgelassenen Fr\u00fchst\u00fcck und einem letzten Gruppenfoto p\u00fcnktlich zur\u00fcck in die Heimat. Die f\u00fcnf Tage waren unheimlich interessant und wir konnten verschiedene andere Kulturen kennenlernen. Projekte wie dieses lassen uns Jugendliche aktiv an der Sozialisation teilhaben und f\u00f6rdern das Gemeinschaftsgef\u00fchl. Herzlichen Dank an die St\u00e4dte Erba, Fellbach und Mei\u00dfen f\u00fcr diese gro\u00dfartige Chance. Vivien Frenzel, Berufliches Gymnasium BSZ Mei\u00dfen &#8211; Radebeul<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[15],"tags":[],"class_list":["post-229","post","type-post","status-publish","format-standard","hentry","category-jugendsymposium"],"translation":{"provider":"WPGlobus","version":"3.0.5","language":"pl","enabled_languages":["de","fr","ja","el","cs","en","pl"],"languages":{"de":{"title":true,"content":true,"excerpt":false},"fr":{"title":false,"content":false,"excerpt":false},"ja":{"title":false,"content":false,"excerpt":false},"el":{"title":false,"content":false,"excerpt":false},"cs":{"title":false,"content":false,"excerpt":false},"en":{"title":false,"content":false,"excerpt":false},"pl":{"title":false,"content":false,"excerpt":false}}},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/spv-meissen.de\/pl\/wp-json\/wp\/v2\/posts\/229","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/spv-meissen.de\/pl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/spv-meissen.de\/pl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/spv-meissen.de\/pl\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/spv-meissen.de\/pl\/wp-json\/wp\/v2\/comments?post=229"}],"version-history":[{"count":4,"href":"https:\/\/spv-meissen.de\/pl\/wp-json\/wp\/v2\/posts\/229\/revisions"}],"predecessor-version":[{"id":1624,"href":"https:\/\/spv-meissen.de\/pl\/wp-json\/wp\/v2\/posts\/229\/revisions\/1624"}],"wp:attachment":[{"href":"https:\/\/spv-meissen.de\/pl\/wp-json\/wp\/v2\/media?parent=229"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/spv-meissen.de\/pl\/wp-json\/wp\/v2\/categories?post=229"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/spv-meissen.de\/pl\/wp-json\/wp\/v2\/tags?post=229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}